{"id":32682,"date":"2020-11-05T10:35:53","date_gmt":"2020-11-05T10:35:53","guid":{"rendered":"https:\/\/www.bredent-implants.com\/perfil-de-la-compania\/"},"modified":"2021-03-05T09:00:18","modified_gmt":"2021-03-05T09:00:18","slug":"perfil-de-la-compania","status":"publish","type":"page","link":"https:\/\/www.bredent-implants.com\/es\/perfil-de-la-compania\/","title":{"rendered":"Perfil de la compa\u00f1\u00eda"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"32682\" class=\"elementor elementor-32682 elementor-9584\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9d70653 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"9d70653\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0423447\" data-id=\"0423447\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cce9bf5 elementor-widget elementor-widget-breadcrumbs\" data-id=\"cce9bf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.bredent-implants.com\/es\/\">Home<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-97fe849 elementor-section-stretched elementor-section-height-min-height elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"97fe849\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6bf64d0\" data-id=\"6bf64d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d07de65 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d07de65\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-72f58d9\" data-id=\"72f58d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1020456 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1020456\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">WE ARE ONE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5b593a elementor-widget elementor-widget-spacer\" data-id=\"b5b593a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eeb2689 elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eeb2689\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-cde9fd2\" data-id=\"cde9fd2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cdddf5d elementor-invisible elementor-widget elementor-widget-image\" data-id=\"cdddf5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"494\" src=\"https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/07\/bredent-medical_company_bg-1024x632.png\" class=\"attachment-large size-large wp-image-32699\" alt=\"\" srcset=\"https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/07\/bredent-medical_company_bg-1024x632.png 1024w, https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/07\/bredent-medical_company_bg-300x185.png 300w, https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/07\/bredent-medical_company_bg-768x474.png 768w, https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/07\/bredent-medical_company_bg.png 1150w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2fd85a5\" data-id=\"2fd85a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c492544 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"c492544\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"494\" src=\"https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/07\/bredent_company_bg-1024x632.png\" class=\"attachment-large size-large wp-image-32704\" alt=\"\" srcset=\"https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/07\/bredent_company_bg-1024x632.png 1024w, https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/07\/bredent_company_bg-300x185.png 300w, https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/07\/bredent_company_bg-768x474.png 768w, https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/07\/bredent_company_bg.png 1150w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-917f88f\" data-id=\"917f88f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-496c643 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"496c643\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"494\" src=\"https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/07\/dcs_company_bg-1024x632.png\" class=\"attachment-large size-large wp-image-32709\" alt=\"\" srcset=\"https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/07\/dcs_company_bg-1024x632.png 1024w, https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/07\/dcs_company_bg-300x185.png 300w, https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/07\/dcs_company_bg-768x474.png 768w, https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/07\/dcs_company_bg.png 1150w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-333b7a7 elementor-section-stretched elementor-section-height-min-height elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"333b7a7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5436d41\" data-id=\"5436d41\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fd35813 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd35813\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ece6088\" data-id=\"ece6088\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-532806b animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"532806b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">WE ARE ONE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2a17f50 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a17f50\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d4462b5\" data-id=\"d4462b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50be2b5 elementor-widget elementor-widget-image\" data-id=\"50be2b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"230\" src=\"https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2021\/02\/company-profile-mobile.png\" class=\"attachment-large size-large wp-image-36796\" alt=\"\" srcset=\"https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2021\/02\/company-profile-mobile.png 800w, https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2021\/02\/company-profile-mobile-300x86.png 300w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9265099 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9265099\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c607a89\" data-id=\"c607a89\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e04473a elementor-widget elementor-widget-heading\" data-id=\"e04473a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Perfil de la empresa - Declaraci\u00f3n de la misi\u00f3n del grupo Bredent <\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c4efe43 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c4efe43\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9424959\" data-id=\"9424959\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f69548d elementor-widget elementor-widget-text-editor\" data-id=\"f69548d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b><span style=\"color: #000000;\">El bredent group<\/span><\/b><\/p>\n<p><span style=\"color: #000000;\">Nosotros, bredent group, somos una empresa de gesti\u00f3n familiar que trabaja a nivel internacional.<\/span><\/p>\n<p><span style=\"color: #000000;\">En bredent group desarrollamos productos individuales \u00f3ptimamente armonizados, soluciones sist\u00e9micas \u2014por ejemplo, en el segmento de la prot\u00e9sica implantar\u2014 y conceptos terap\u00e9uticos \u00abmade in Germany\u00bb, y los fabricamos nosotros mismos. Esto permite a odont\u00f3logos y t\u00e9cnicos dentales confeccionar y conservar con un coste razonable sustitutos dentales de gran valor, est\u00e9ticos e higi\u00e9nicos desde el punto de Vista periodontal.<\/span><\/p>\n<p><span style=\"color: #000000;\">Nuestro af\u00e1n es estar entre los mejores. Por ello nuestros empleados siempre est\u00e1n dispuestos a prestar el mejor servicio a sus clientes y los pacientes de \u00e9stos, actuando con la flexibilidad necesaria y una mentalidad abierta.<\/span><\/p>\n<p><span style=\"color: #000000;\">Con nuestra competencia y capacidad innovadora, somos un referente en el mercado dental.<\/span><\/p>\n<p><span style=\"color: #000000;\">Cultivamos nuestra cultura corporativa, la relaci\u00f3n de colaboraci\u00f3n con nuestros clientes y socios comerciales y las actividades que proporcionan beneficios de acuerdo con nuestros valores, ya definidos en 1995, como fundamento que nos permita alcanzar nuestros objetivos y mantener buenas relaciones a largo plazo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b><span style=\"color: #000000;\">Somos eficientes<\/span><\/b><br \/><span style=\"color: #000000;\">Estamos convencidos de los beneficios que reporta nuestro trabajo y, por lo tanto, nos gusta esforzarnos en ser cada vez m\u00e1s eficientes.<\/span><\/p>\n<p><b><span style=\"color: #000000;\">Nos gusta colaborar<\/span><\/b><br \/><span style=\"color: #000000;\">Somos abiertos y justos en nuestra colaboraci\u00f3n. As\u00ed creamos confianza mutua.<\/span><\/p>\n<p><b><span style=\"color: #000000;\">Marcamos tendencia<\/span><\/b><br \/><span style=\"color: #000000;\">Nuestra competencia, flexibilidad y apertura de miras nos permiten proporcionar soluciones beneficiosas innovadoras.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b><span style=\"color: #000000;\">Lo que somos para nuestros clientes:<\/span><\/b><\/p>\n<p><span style=\"color: #000000;\">Para nuestros clientes somos un socio de negocios que ofrece beneficios gracias a nuestra eficiencia y nuestras soluciones. Todas nuestras actividades son reflejo de esta aspiraci\u00f3n. Nos preocupamos por nuestros clientes y sus necesidades<\/span><br \/><span style=\"color: #000000;\">\u2013 Nos mantenemos constantemente informados sobre ellos y sobre los problemas y deseos de sus pacientes. El cumplimiento de reglamentos, normas y leyes pertinentes es algo que consideramos natural.<\/span><\/p>\n<p><b><span style=\"color: #000000;\">Lo que esto significa para nuestra organizaci\u00f3n y nuestra cooperaci\u00f3n:<\/span><\/b><\/p>\n<p><span style=\"color: #000000;\">Vemos en los cambios y las nuevas exigencias oportunidades y retos para reaccionar con rapidez y flexibilidad. Por eso, la capacidad de cambiar es un importante requisito previo para nuestro \u00e9xito. Una de las consecuencias de esto es que nuestra organizaci\u00f3n se halla en permanente transformaci\u00f3n para ser m\u00e1s r\u00e1pida y econ\u00f3mica y poder satisfacer las crecientes demandas de nuestro \u00e1mbito comercial, as\u00ed como de nuestros clientes y sus pacientes.<\/span><\/p>\n<p><b><span style=\"color: #000000;\">Lo que somos para nuestros empleados:<\/span><\/b><\/p>\n<p><span style=\"color: #000000;\">Mostramos compromiso y sentido de la responsabilidad en cada tarea, como individuos y como equipo. Todos cumplimos con nuestras obligaciones. Todos nos comprometemos a alcanzar los objetivos de la empresa y a materializar los valores de la empresa. A cambio recibimos seguridad, oportunidades para el desarrollo personal y libertad para el crecimiento profesional. Al utilizar y ampliar nuestros conocimientos compartidos, establecemos las bases para el \u00e9xito del futuro.<\/span><\/p>\n<p><b><span style=\"color: #000000;\">Lo que esto significa para nuestra relaci\u00f3n con la sociedad:<\/span><\/b><\/p>\n<p><span style=\"color: #000000;\">Es algo natural para nosotros, como empresa, aportar de manera duradera algo positivo a la sociedad y al medio ambiente.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">Nuestras ganancias son la base para nuevas inversiones que marcan tendencia y por lo tanto sirven para asegurar puestos de trabajo en l\u00ednea con nuestros objetivos y valores para el beneficio de nuestros clientes.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><em>La direcci\u00f3n y los accionistas <\/em><\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>WE ARE ONE WE ARE ONE Perfil de la empresa &#8211; Declaraci\u00f3n de la misi\u00f3n del grupo Bredent El bredent group Nosotros, bredent group, somos una empresa de gesti\u00f3n familiar que trabaja a nivel internacional. En bredent group desarrollamos productos individuales \u00f3ptimamente armonizados, soluciones sist\u00e9micas \u2014por ejemplo, en el segmento de la prot\u00e9sica implantar\u2014 y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":19045,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-32682","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Perfil de la compa\u00f1\u00eda - bredent-implants<\/title>\n<meta name=\"description\" content=\"WE ARE ONE WE ARE ONE Perfil de la empresa - Declaraci\u00f3n de la misi\u00f3n del grupo Bredent El bredent group Nosotros, bredent group, somos una empresa de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bredent-implants.com\/es\/perfil-de-la-compania\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perfil de la compa\u00f1\u00eda - bredent-implants\" \/>\n<meta property=\"og:description\" content=\"WE ARE ONE WE ARE ONE Perfil de la empresa - Declaraci\u00f3n de la misi\u00f3n del grupo Bredent El bredent group Nosotros, bredent group, somos una empresa de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bredent-implants.com\/es\/perfil-de-la-compania\/\" \/>\n<meta property=\"og:site_name\" content=\"bredent-implants\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bredent-group-International-766435650174845\/?ref=bookmarks\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-05T09:00:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/03\/bredent-group-Black-Logo-PNG-file.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1579\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bredent-implants.com\\\/es\\\/perfil-de-la-compania\\\/\",\"url\":\"https:\\\/\\\/www.bredent-implants.com\\\/es\\\/perfil-de-la-compania\\\/\",\"name\":\"Perfil de la compa\u00f1\u00eda - bredent-implants\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bredent-implants.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bredent-implants.com\\\/es\\\/perfil-de-la-compania\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bredent-implants.com\\\/es\\\/perfil-de-la-compania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bredent-implants.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/bredent-group-Black-Logo-PNG-file.png\",\"datePublished\":\"2020-11-05T10:35:53+00:00\",\"dateModified\":\"2021-03-05T09:00:18+00:00\",\"description\":\"WE ARE ONE WE ARE ONE Perfil de la empresa - Declaraci\u00f3n de la misi\u00f3n del grupo Bredent El bredent group Nosotros, bredent group, somos una empresa de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bredent-implants.com\\\/es\\\/perfil-de-la-compania\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bredent-implants.com\\\/es\\\/perfil-de-la-compania\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.bredent-implants.com\\\/es\\\/perfil-de-la-compania\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bredent-implants.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/bredent-group-Black-Logo-PNG-file.png\",\"contentUrl\":\"https:\\\/\\\/www.bredent-implants.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/bredent-group-Black-Logo-PNG-file.png\",\"width\":1579,\"height\":330,\"caption\":\"bredent group logo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bredent-implants.com\\\/es\\\/perfil-de-la-compania\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bredent-implants.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perfil de la compa\u00f1\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bredent-implants.com\\\/#website\",\"url\":\"https:\\\/\\\/www.bredent-implants.com\\\/\",\"name\":\"bredent-implants\",\"description\":\"bredent medical implants\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bredent-implants.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bredent-implants.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bredent-implants.com\\\/#organization\",\"name\":\"bredent GmbH & Co.KG\",\"url\":\"https:\\\/\\\/www.bredent-implants.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.bredent-implants.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bredent-implants.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/bredent-group-Black-Logo-PNG-file.png\",\"contentUrl\":\"https:\\\/\\\/www.bredent-implants.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/bredent-group-Black-Logo-PNG-file.png\",\"width\":1579,\"height\":330,\"caption\":\"bredent GmbH & Co.KG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bredent-implants.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bredent-group-International-766435650174845\\\/?ref=bookmarks\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/bredentgroup\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perfil de la compa\u00f1\u00eda - bredent-implants","description":"WE ARE ONE WE ARE ONE Perfil de la empresa - Declaraci\u00f3n de la misi\u00f3n del grupo Bredent El bredent group Nosotros, bredent group, somos una empresa de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bredent-implants.com\/es\/perfil-de-la-compania\/","og_locale":"es_ES","og_type":"article","og_title":"Perfil de la compa\u00f1\u00eda - bredent-implants","og_description":"WE ARE ONE WE ARE ONE Perfil de la empresa - Declaraci\u00f3n de la misi\u00f3n del grupo Bredent El bredent group Nosotros, bredent group, somos una empresa de","og_url":"https:\/\/www.bredent-implants.com\/es\/perfil-de-la-compania\/","og_site_name":"bredent-implants","article_publisher":"https:\/\/www.facebook.com\/bredent-group-International-766435650174845\/?ref=bookmarks","article_modified_time":"2021-03-05T09:00:18+00:00","og_image":[{"width":1579,"height":330,"url":"https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/03\/bredent-group-Black-Logo-PNG-file.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bredent-implants.com\/es\/perfil-de-la-compania\/","url":"https:\/\/www.bredent-implants.com\/es\/perfil-de-la-compania\/","name":"Perfil de la compa\u00f1\u00eda - bredent-implants","isPartOf":{"@id":"https:\/\/www.bredent-implants.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bredent-implants.com\/es\/perfil-de-la-compania\/#primaryimage"},"image":{"@id":"https:\/\/www.bredent-implants.com\/es\/perfil-de-la-compania\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/03\/bredent-group-Black-Logo-PNG-file.png","datePublished":"2020-11-05T10:35:53+00:00","dateModified":"2021-03-05T09:00:18+00:00","description":"WE ARE ONE WE ARE ONE Perfil de la empresa - Declaraci\u00f3n de la misi\u00f3n del grupo Bredent El bredent group Nosotros, bredent group, somos una empresa de","breadcrumb":{"@id":"https:\/\/www.bredent-implants.com\/es\/perfil-de-la-compania\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bredent-implants.com\/es\/perfil-de-la-compania\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bredent-implants.com\/es\/perfil-de-la-compania\/#primaryimage","url":"https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/03\/bredent-group-Black-Logo-PNG-file.png","contentUrl":"https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/03\/bredent-group-Black-Logo-PNG-file.png","width":1579,"height":330,"caption":"bredent group logo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bredent-implants.com\/es\/perfil-de-la-compania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bredent-implants.com\/es\/"},{"@type":"ListItem","position":2,"name":"Perfil de la compa\u00f1\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/www.bredent-implants.com\/#website","url":"https:\/\/www.bredent-implants.com\/","name":"bredent-implants","description":"bredent medical implants","publisher":{"@id":"https:\/\/www.bredent-implants.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bredent-implants.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.bredent-implants.com\/#organization","name":"bredent GmbH & Co.KG","url":"https:\/\/www.bredent-implants.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bredent-implants.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/03\/bredent-group-Black-Logo-PNG-file.png","contentUrl":"https:\/\/www.bredent-implants.com\/wp-content\/uploads\/2019\/03\/bredent-group-Black-Logo-PNG-file.png","width":1579,"height":330,"caption":"bredent GmbH & Co.KG"},"image":{"@id":"https:\/\/www.bredent-implants.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bredent-group-International-766435650174845\/?ref=bookmarks","https:\/\/www.youtube.com\/user\/bredentgroup"]}]}},"_links":{"self":[{"href":"https:\/\/www.bredent-implants.com\/es\/wp-json\/wp\/v2\/pages\/32682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bredent-implants.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bredent-implants.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bredent-implants.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bredent-implants.com\/es\/wp-json\/wp\/v2\/comments?post=32682"}],"version-history":[{"count":0,"href":"https:\/\/www.bredent-implants.com\/es\/wp-json\/wp\/v2\/pages\/32682\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bredent-implants.com\/es\/wp-json\/wp\/v2\/media\/19045"}],"wp:attachment":[{"href":"https:\/\/www.bredent-implants.com\/es\/wp-json\/wp\/v2\/media?parent=32682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}